{"id":990,"date":"2023-11-30T17:49:21","date_gmt":"2023-11-30T20:49:21","guid":{"rendered":"https:\/\/meiremendesjoias.com.br\/novo\/?post_type=product&#038;p=990"},"modified":"2023-12-08T11:41:04","modified_gmt":"2023-12-08T14:41:04","slug":"berloque-flor","status":"publish","type":"product","link":"https:\/\/meiremendesjoias.com.br\/novo\/produto\/berloque-flor\/","title":{"rendered":"Berloque Flor"},"content":{"rendered":"<p>Berloque flor esmaltada, Vivara e Pandora Inspired, banhado a r\u00f3dio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berloque flor esmaltada, Vivara e Pandora Inspired, banhado a r\u00f3dio.<\/p>\n","protected":false},"featured_media":1020,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[220],"product_tag":[487,488,483,33,34,489,400,224],"class_list":{"0":"post-990","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pingentes","7":"product_tag-banhado","8":"product_tag-berloques","9":"product_tag-charms","10":"product_tag-esmaltada","11":"product_tag-flor","12":"product_tag-life-vivara-inspired","13":"product_tag-pandora-inspired","14":"product_tag-pingentes","16":"first","17":"instock","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product\/990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/comments?post=990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/media\/1020"}],"wp:attachment":[{"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/media?parent=990"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product_brand?post=990"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product_cat?post=990"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product_tag?post=990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}