{"id":994,"date":"2023-11-30T17:49:22","date_gmt":"2023-11-30T20:49:22","guid":{"rendered":"https:\/\/meiremendesjoias.com.br\/novo\/?post_type=product&#038;p=994"},"modified":"2023-12-08T11:40:00","modified_gmt":"2023-12-08T14:40:00","slug":"berloque-girafa","status":"publish","type":"product","link":"https:\/\/meiremendesjoias.com.br\/novo\/produto\/berloque-girafa\/","title":{"rendered":"Berloque Girafa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Berloque girafa Vivara e Pandora Inspired, banhado a r\u00f3dio.<\/p>\n","protected":false},"featured_media":1024,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[220],"product_tag":[534,487,488,483,59,535,489,400,224],"class_list":{"0":"post-994","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pingentes","7":"product_tag-animal","8":"product_tag-banhado","9":"product_tag-berloques","10":"product_tag-charms","11":"product_tag-garantia","12":"product_tag-girafa","13":"product_tag-life-vivara-inspired","14":"product_tag-pandora-inspired","15":"product_tag-pingentes","17":"first","18":"instock","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product\/994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/comments?post=994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/media\/1024"}],"wp:attachment":[{"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/media?parent=994"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product_brand?post=994"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product_cat?post=994"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meiremendesjoias.com.br\/novo\/wp-json\/wp\/v2\/product_tag?post=994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}